{"id":1968,"date":"2019-05-13T18:32:15","date_gmt":"2019-05-13T16:32:15","guid":{"rendered":"http:\/\/dellevenezie.it\/?page_id=1968"},"modified":"2023-11-06T09:48:15","modified_gmt":"2023-11-06T08:48:15","slug":"homepage-2","status":"publish","type":"page","link":"https:\/\/dellevenezie.it\/en\/homepage-2\/","title":{"rendered":"Homepage"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_class=&#8221;dv-home-mainrow&#8221;][vc_column][vc_row_inner][vc_column_inner el_id=&#8221;colonna-top-notice&#8221; css=&#8221;.vc_custom_1697825599264{background-color: #fd9826 !important;}&#8221;][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\"><strong>Delle Venezie DOC International Forum<\/strong><\/span><br \/>\n<span style=\"color: #ffffff;\">Verona, november 4th, 2023<\/span><br \/>\n<span style=\"color: #000000;\"><a style=\"color: #000000;\" href=\"https:\/\/dellevenezie.it\/en\/delle-venezie-doc-international-forum-verona-november-4-2023\/\">Click here for info and registration<\/a><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner]\n    <section class=\"home page-section overlay-dark-alpha-50\" data-background=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/04\/pinot-grigio-doc-delle-venezie-home-img-v3.jpg\">\n    <div class=\"table-content\"> \n    <div class=\"table-center-text\">\n    <div class=\"container\"> \n    <h2 class=\"font-face1 heading1 white-color mb-40 mb-xs-30\">Seal of wonderful experiences<\/h2>\n    <h1 class=\"font-face1 heading2 white-color mb-40 mb-xs-30\"><b>Pinot Grigio delle Venezie<\/b><\/h1>\n    <\/div>\n    <\/div>\n    <\/div>\n    <\/section>\n    <section class=\"page-section black-section overlay-dark-alpha-50 big-section\" data-background=\"\">\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"col-sm-6 offset-sm-3 text-center\">    \n            <h2 class=\"heading5 mt-0 font-face1 white-color fw700\">Open Pinot Grigio delle Venezie DOC<\/h2>\n            <p class=\"white-color\">and experience a wonderful world.<br \/>\nShaped by a unique territory that includes Veneto, Trentino and Friuli Venezia Giulia. Everything here is special: from the microclimate to the traditions, from history to art. So is the wine that expresses them. Pinot Grigio delle Venezie: the DOC certified wonderful.<\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>[vc_video link=&#8221;https:\/\/vimeo.com\/681487502\/0c399a5f17&#8243; align=&#8221;center&#8221; css=&#8221;.vc_custom_1671806603483{margin-bottom: 0px !important;background-image: url(https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/12\/en-wonderful-background-video.jpg?id=5327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;]\n    <section class=\"page-section black-section overlay-dark-alpha-50 big-section\" data-background=\"\">\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"col-sm-6 offset-sm-3 text-center\">    \n            <h2 class=\"heading5 mt-0 font-face1 white-color fw700\">Pinot Grigio delle VENEZIE DOC<\/h2>\n            <p class=\"white-color\">is produced in four types, each with a unique and special taste<\/p><a class=\"icon-animate btn big bg-color white-color wow zoomInUp\" href=\"https:\/\/dellevenezie.it\/en\/types\/\"><span>LEARN MORE<\/span><\/a>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section><section class=\"page-section big-section\">\n    <div class=\"shadow-title shadow-gray unselectable parallax-1\">ABOUT US<\/div>\n    <div class=\"container relative\">\n    <h2 class=\"font-face1 section-heading fw800 mt-0 mb-60 mb-sm-40\">THE CONSORTIUM<\/h2>\n    <div class=\"row\">\n    <div class=\"col-md-4 col-sm-6 mb-sm-40 mb-xs-30\">\n    <img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/03\/pinot-grigio-grapes.jpg\" alt=\"\">\n    <\/div>\n    <div class=\"col-md-4 mb-sm-40 mb-xs-30\">\n    <div class=\"block-container font-face1 fw100 light-text\">Protecting, enhancing and promoting Pinot grigio: with these objectives the Consorzio DOC delle Venezie brings together all the operators of the production chain of Triveneto Pinot grigio to guarantee and certify the quality and origin of our wine.<br \/>\n<b>Find out more about our work and our passion.<\/b><\/div>\n    <\/div>\n    <div class=\"col-md-4 col-sm-6 mb-sm-40 mb-xs-30\">\n    <div class=\"light-text\"><b>We protect and enhance <\/b> Pinot grigio delle Venezie designation of origin<\/p>\n<p><b> We strengthen the promotion and development <\/b> of the wine production chain of the territories of Pinot Grigio.<\/p>\n<p><b> We guarantee the respect <\/b> of the best quality parameters and the traceability of our wine.<\/div>\n    <\/div>\n    <\/div>\n    <\/div>\n    <\/section>[vc_separator]\n\n    <section class=\"page-section big-section\"> \n      <div class=\"shadow-title shadow-gray unselectable parallax-1\">Activities<\/div>\n      <div class=\"container\"> \n        <div class=\"row\"> \n          <div class=\"col-md-6 offset-md-3 mb-60 mb-sm-40 text-center\">\n            <h2 class=\"font-face1 section-heading fw800 mt-0text-center\">Activities<\/h2>\n            <p class=\"light-text\">Consorzio delle Venezie DOC established in April 2017 but has already achieved several important objectives which are fundamental for the development of activities to protect the denomination of origin of the Pinot grigio of Triveneto. Current work in progress, great goals for the future.<\/p>\n          <\/div>\n        <\/div>\n        <div class=\"row\">\n          <div class=\"col-md-3 col-sm-6\">\n            <div class=\"alt-block-item text-center\">\n              <object data=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/089-telescope.svg\" type=\"image\/svg+xml\" class=\"icon-media opacity8\"><\/object>\n              <h3 class=\"font-face1 heading6 mb-20\">PROTECTION<\/h3>\n              <a href=\"javascript:void(0)\" class=\"process-detail btn btn-icon bg-white\"><i class=\"lnr lnr-plus-circle\"><\/i><\/a>\n              <div class=\"alt-block-description\">We protect Pinot grigio, an international variety that sees 85% of its production in Northeast Italy, 43% of the global one.<\/div>\n            <\/div>\n          <\/div>\n          <div class=\"col-md-3 col-sm-6\">\n            <div class=\"alt-block-item text-center\">\n              <object data=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/005-check.svg\" type=\"image\/svg+xml\" class=\"icon-media opacity8\"><\/object>\n              <h3 class=\"font-face1 heading6 mb-20\">CERTIFICATION<\/h3>\n              <a href=\"javascript:void(0)\" class=\"process-detail btn btn-icon bg-white\"><i class=\"lnr lnr-plus-circle\"><\/i><\/a>\n              <div class=\"alt-block-description\">Triveneta Certificazioni, a dedicated control body, is responsible of the certicication of Pinot grigio delle Venezie from the entire Triveneto region by controlling the entire production chain<\/div>\n            <\/div>\n          <\/div>\n          <div class=\"col-md-3 col-sm-6\">\n            <div class=\"alt-block-item text-center\">\n              <object data=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/031-gears.svg\" type=\"image\/svg+xml\" class=\"icon-media opacity8\"><\/object>\n              <h3 class=\"font-face1 heading6 mb-20\">PRODUCTION<\/h3>\n              <a href=\"javascript:void(0)\" class=\"process-detail btn btn-icon bg-white\"><i class=\"lnr lnr-plus-circle\"><\/i><\/a>\n              <div class=\"alt-block-description\">The Production Specification guarantee the quality of the Pinot grigio delle Venezie DOC. The Consortium represents and protects producers who want to produce quality Pinot grigio.<\/div>\n            <\/div>\n          <\/div>\n          <div class=\"col-md-3 col-sm-6\">\n            <div class=\"alt-block-item text-center\">\n              <object data=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/034-megaphone.svg\" type=\"image\/svg+xml\" class=\"icon-media\"><\/object>\n              <h3 class=\"font-face1 heading6 mb-20\">PROMOTION<\/h3>\n              <a href=\"javascript:void(0)\" class=\"process-detail btn btn-icon bg-white\"><i class=\"lnr lnr-plus-circle\"><\/i><\/a>\n              <div class=\"alt-block-description\">Informing, promoting and recounting the denomination in the world to introduce global consumers who are fond of this variety the qualitative path taken by the production chain of Pinot grigio delle Venezie DOC<\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>\n    <section class=\"page-section black-section overlay-dark-alpha-50 big-section\" data-background=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/vigneto.jpg\">\n      <div class=\"container\">\n        <div class=\"row\">\n          <div class=\"col-sm-6 offset-sm-3 text-center\">    \n            <h2 class=\"heading5 mt-0 font-face1 white-color fw700\"><\/h2>\n            <p class=\"white-color\"><\/p>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>[vc_separator]\n    <section class=\"page-section big-section\"> \n      <div class=\"shadow-title shadow-gray unselectable parallax-1\">ASSOCIATED WINERIES<\/div>\n      <div class=\"container\">\n        <div class=\"row\"> \n          <div class=\"col-md-6 offset-md-3 mb-60 mb-sm-40 text-center\">\n            <h2 class=\"font-face1 section-heading fw800 mt-0 text-center\">A common goal<\/h2>\n            <p class=\"light-text\">DOC delle Venezie Consorzio associates all the operators of the production chain of Pinot grigio from Triveneto to guarantee and certify the quality and origin of our wine.<\/p> \n          <\/div>\n        <\/div>\n        <div class=\"row\">\n          <div class=\"col-md-12\">\n            <div class=\"block-wraper\">\n              <div class=\"slick-container clients-slider\">\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/annodomini.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/index-1-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/albano_armani-e1645284162214.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2023\/01\/def.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/images.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/astoria.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/bertoia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/logo.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/beato_bartolomeo_breganze.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bennati.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bidoli-e1645284218488.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bonotto-delle-tezze.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/borgo-molino.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/borgo-stajnbech-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/Borgoluce.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bortoluzzi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bosco-del-corner.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/bosco_del_merlo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/bosco.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/botter.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/05\/0-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/52093996_2184786855118472_8639819546221346816_o.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Cabert-e1645283975451.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/campagnola.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/10\/cantina3vlogo-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/CantinaColliEuganei-e1645284063406.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/cantina-del-terraglio-e1645284129792.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/avio.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Cantina-Cona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/conegliano.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/custoza.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cantina.mareno.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/monteforte.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cantinasocialeormelle.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/CANTINA-RAUSCEDO-logo-INGRANDITO-epigrafe-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/soave.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/17264194_1289621557797481_8125379556943226522_n.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montelliana.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ramuscello.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ala.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/non-so.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/tezze.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/valpantena.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Logo-Borga-DEFINITIVO-PDF-VETTORIALE_pages-to-jpg-0001-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/collis.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ermes.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/191626453_3979665698795040_5677872243282611814_n.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2025\/12\/Logo-Cantine-Sgarzi-Luigi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/caorsa.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/casa-girelli-logo-2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/casa-modin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/casa-paladin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/caviro.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cavit.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/z-EJlE_n-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/collis-e1645284191498.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/conselve.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/consorzio-agrario.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/contri.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cormons.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/corte-giara.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/corte-moschina.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/dalcero-family.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/villadecordi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/deliborti.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/dominio-bagnoli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/09\/DOMUS-VINI_logo-red-web-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/trademark.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/enoitalia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/enotria.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ermacora.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/faccioli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/faccioli2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/farina.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/fidora.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/franz-haas.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2021\/01\/190130-log-da-lozzo-A4-01_Tavola-disegno-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/fm-logo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/GIV.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/magredi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/logo-2-e1645283934811.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2023\/10\/1181-copia-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/kris-1-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/feudi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Logo-La-Delizia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/54213638_2347260982230327_2903519353771130880_o.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/lavis.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/09\/600433_405407232833952_2025134920_n-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/06\/azienda_agricola_le_rive.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Cantina-Cona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Gaierhof-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/felluga.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/02\/logo_vini_marocchesa-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Masottina-Ai-Palazzi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/mezzacorona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/mgm.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/modeano.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/roari-2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/monteci.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montelvini.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montemagrino.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montetondo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/cantina-mori.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/verga.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/mezzacorona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/opitergium.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/paladin-giovanni.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Pasqua-2025.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/perlage.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/piazza.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/piera.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/pighin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/17342727_10155076307179501_1257358271606992918_n.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/porcia_logo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/512x512bb.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/recchia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/amadio.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/rechsteiner.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/roeno.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/rovere.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ruffino.png.jpeg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/08\/92359485_796181840907163_1727782325757935616_o-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/sanbartolomeo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/santasofia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/sartori.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/rino-sartori.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/savoian.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/schenk2-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/scriani.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Immagine-2025-03-04-160542.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2025\/12\/Logo-Serena-Wines.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/sessantacampi-a-name.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/tamburino-e1645284094121.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/grimani.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/06\/30716433_1940245026039972_7102013698427998173_n-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/salvaterra.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/11121.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/terredirai.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/04\/logotezza-mod-0-logo-azienda-1-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/51180432_1862656983845723_917084614160285696_n.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/48360256_2010395552413421_3593575509948104704_n.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/tommasi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/trevisana.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/valdadige.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vendrame.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vivo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vignaioli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2025\/12\/Logo-Villa-degli-Olmi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/villa-mattielli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/logo_black-e1645283861383.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vitevis.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/47576013_2154199691310408_5749055888837050368_o.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/logza_7_2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/zonin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/annodomini.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/index-1-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/albano_armani-e1645284162214.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2023\/01\/def.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/images.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/astoria.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/bertoia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/logo.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/beato_bartolomeo_breganze.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bennati.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bidoli-e1645284218488.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bonotto-delle-tezze.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/borgo-molino.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/borgo-stajnbech-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/Borgoluce.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bortoluzzi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/bosco-del-corner.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/bosco_del_merlo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/bosco.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/botter.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/05\/0-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/52093996_2184786855118472_8639819546221346816_o.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Cabert-e1645283975451.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/campagnola.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/10\/cantina3vlogo-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/CantinaColliEuganei-e1645284063406.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/12\/cantina-del-terraglio-e1645284129792.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/avio.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Cantina-Cona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/conegliano.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/custoza.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cantina.mareno.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/monteforte.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cantinasocialeormelle.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/CANTINA-RAUSCEDO-logo-INGRANDITO-epigrafe-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/soave.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/17264194_1289621557797481_8125379556943226522_n.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montelliana.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ramuscello.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ala.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/non-so.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/tezze.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/valpantena.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Logo-Borga-DEFINITIVO-PDF-VETTORIALE_pages-to-jpg-0001-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/collis.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ermes.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/191626453_3979665698795040_5677872243282611814_n.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2025\/12\/Logo-Cantine-Sgarzi-Luigi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/caorsa.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/casa-girelli-logo-2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/casa-modin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/casa-paladin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/caviro.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cavit.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/z-EJlE_n-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2018\/11\/collis-e1645284191498.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/conselve.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/consorzio-agrario.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/contri.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/cormons.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/corte-giara.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/corte-moschina.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/dalcero-family.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/villadecordi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/deliborti.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/dominio-bagnoli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/09\/DOMUS-VINI_logo-red-web-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/trademark.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/enoitalia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/enotria.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ermacora.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/faccioli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/faccioli2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/farina.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/fidora.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/franz-haas.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2021\/01\/190130-log-da-lozzo-A4-01_Tavola-disegno-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/fm-logo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/GIV.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/magredi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/logo-2-e1645283934811.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2023\/10\/1181-copia-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/kris-1-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/feudi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Logo-La-Delizia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/54213638_2347260982230327_2903519353771130880_o.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/lavis.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/09\/600433_405407232833952_2025134920_n-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/06\/azienda_agricola_le_rive.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Cantina-Cona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Gaierhof-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/felluga.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/02\/logo_vini_marocchesa-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/Masottina-Ai-Palazzi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/mezzacorona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/mgm.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/modeano.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/roari-2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/monteci.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montelvini.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montemagrino.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/montetondo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/cantina-mori.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/verga.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/mezzacorona.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/opitergium.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/paladin-giovanni.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Pasqua-2025.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/perlage.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/piazza.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/piera.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/pighin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/17342727_10155076307179501_1257358271606992918_n.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/porcia_logo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/512x512bb.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/recchia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/amadio.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/rechsteiner.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/roeno.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/rovere.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/ruffino.png.jpeg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/08\/92359485_796181840907163_1727782325757935616_o-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/sanbartolomeo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/santasofia.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/sartori.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/rino-sartori.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/savoian.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/schenk2-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/scriani.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/03\/Immagine-2025-03-04-160542.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2025\/12\/Logo-Serena-Wines.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/sessantacampi-a-name.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/tamburino-e1645284094121.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/grimani.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/06\/30716433_1940245026039972_7102013698427998173_n-1.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/salvaterra.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/11121.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/terredirai.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/04\/logotezza-mod-0-logo-azienda-1-1.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/51180432_1862656983845723_917084614160285696_n.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/48360256_2010395552413421_3593575509948104704_n.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/tommasi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/trevisana.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/valdadige.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vendrame.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vivo.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vignaioli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2025\/12\/Logo-Villa-degli-Olmi.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/villa-mattielli.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2020\/02\/logo_black-e1645283861383.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/vitevis.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/04\/47576013_2154199691310408_5749055888837050368_o.png\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/logza_7_2.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n                <div class=\"slick-item\">\n                  <div><a href=\"\/en\/wineries\"><img decoding=\"async\" src=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2019\/01\/zonin.jpg\" alt=\"\" \/><\/a><\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n            <div class=\"client-navigation-bottom\">\n              <div class=\"client-left\"><i class=\"lnr lnr-arrow-left\"><\/i><\/div>\n              <div class=\"client-right\"><i class=\"lnr lnr-arrow-right\"><\/i><\/div>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/section>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;dv-home-mainrow&#8221;][vc_column][vc_row_inner][vc_column_inner el_id=&#8221;colonna-top-notice&#8221; css=&#8221;.vc_custom_1697825599264{background-color: #fd9826 !important;}&#8221;][vc_column_text] Delle Venezie DOC International Forum Verona, november 4th, 2023 Click here for info and registration [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_video link=&#8221;https:\/\/vimeo.com\/681487502\/0c399a5f17&#8243; align=&#8221;center&#8221; css=&#8221;.vc_custom_1671806603483{margin-bottom: 0px !important;background-image: url(https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/12\/en-wonderful-background-video.jpg?id=5327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_separator][vc_separator][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/homepage-template.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1968","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homepage | Consorzio vini DOC delle Venezie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dellevenezie.it\/en\/homepage-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Homepage | Consorzio vini DOC delle Venezie\" \/>\n<meta property=\"og:description\" content=\"[vc_row el_class=&#8221;dv-home-mainrow&#8221;][vc_column][vc_row_inner][vc_column_inner el_id=&#8221;colonna-top-notice&#8221; css=&#8221;.vc_custom_1697825599264{background-color: #fd9826 !important;}&#8221;][vc_column_text] Delle Venezie DOC International Forum Verona, november 4th, 2023 Click here for info and registration [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_video link=&#8221;https:\/\/vimeo.com\/681487502\/0c399a5f17&#8243; align=&#8221;center&#8221; css=&#8221;.vc_custom_1671806603483{margin-bottom: 0px !important;background-image: url(https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/12\/en-wonderful-background-video.jpg?id=5327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_separator][vc_separator][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dellevenezie.it\/en\/homepage-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio vini DOC delle Venezie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pinotgrigio.wine\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T08:48:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dellevenezie.it\/wp-content\/uploads\/2026\/03\/Pinot-Grigio-DOC-delle-Venezie-Trieste-1200x675-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@delleVenezie\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/en\\\/homepage-2\\\/\",\"url\":\"https:\\\/\\\/dellevenezie.it\\\/en\\\/homepage-2\\\/\",\"name\":\"Homepage | Consorzio vini DOC delle Venezie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/#website\"},\"datePublished\":\"2019-05-13T16:32:15+00:00\",\"dateModified\":\"2023-11-06T08:48:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/en\\\/homepage-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dellevenezie.it\\\/en\\\/homepage-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/en\\\/homepage-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dellevenezie.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/#website\",\"url\":\"https:\\\/\\\/dellevenezie.it\\\/\",\"name\":\"Pinot Grigio DOC delle Venezie | sito ufficiale\",\"description\":\"Drink Italian, feel Italian\",\"publisher\":{\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dellevenezie.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/#organization\",\"name\":\"Consorzio vini DOC delle Venezie\",\"url\":\"https:\\\/\\\/dellevenezie.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dellevenezie.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-Consorzio-DOC-Delle-Venezie-cerchio-fondo-bianco-600px.png\",\"contentUrl\":\"https:\\\/\\\/dellevenezie.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-Consorzio-DOC-Delle-Venezie-cerchio-fondo-bianco-600px.png\",\"width\":600,\"height\":599,\"caption\":\"Consorzio vini DOC delle Venezie\"},\"image\":{\"@id\":\"https:\\\/\\\/dellevenezie.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pinotgrigio.wine\",\"https:\\\/\\\/x.com\\\/delleVenezie\",\"https:\\\/\\\/www.instagram.com\\\/dellevenezie\\\/\",\"https:\\\/\\\/www.facebook.com\\\/dellevenezie\",\"https:\\\/\\\/www.youtube.com\\\/@dellevenezie\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homepage | Consorzio vini DOC delle Venezie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dellevenezie.it\/en\/homepage-2\/","og_locale":"en_US","og_type":"article","og_title":"Homepage | Consorzio vini DOC delle Venezie","og_description":"[vc_row el_class=&#8221;dv-home-mainrow&#8221;][vc_column][vc_row_inner][vc_column_inner el_id=&#8221;colonna-top-notice&#8221; css=&#8221;.vc_custom_1697825599264{background-color: #fd9826 !important;}&#8221;][vc_column_text] Delle Venezie DOC International Forum Verona, november 4th, 2023 Click here for info and registration [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_video link=&#8221;https:\/\/vimeo.com\/681487502\/0c399a5f17&#8243; align=&#8221;center&#8221; css=&#8221;.vc_custom_1671806603483{margin-bottom: 0px !important;background-image: url(https:\/\/dellevenezie.it\/wp-content\/uploads\/2022\/12\/en-wonderful-background-video.jpg?id=5327) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_separator][vc_separator][\/vc_column][\/vc_row]","og_url":"https:\/\/dellevenezie.it\/en\/homepage-2\/","og_site_name":"Consorzio vini DOC delle Venezie","article_publisher":"https:\/\/www.facebook.com\/pinotgrigio.wine","article_modified_time":"2023-11-06T08:48:15+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dellevenezie.it\/wp-content\/uploads\/2026\/03\/Pinot-Grigio-DOC-delle-Venezie-Trieste-1200x675-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@delleVenezie","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dellevenezie.it\/en\/homepage-2\/","url":"https:\/\/dellevenezie.it\/en\/homepage-2\/","name":"Homepage | Consorzio vini DOC delle Venezie","isPartOf":{"@id":"https:\/\/dellevenezie.it\/#website"},"datePublished":"2019-05-13T16:32:15+00:00","dateModified":"2023-11-06T08:48:15+00:00","breadcrumb":{"@id":"https:\/\/dellevenezie.it\/en\/homepage-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dellevenezie.it\/en\/homepage-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dellevenezie.it\/en\/homepage-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dellevenezie.it\/en\/"},{"@type":"ListItem","position":2,"name":"Homepage"}]},{"@type":"WebSite","@id":"https:\/\/dellevenezie.it\/#website","url":"https:\/\/dellevenezie.it\/","name":"Pinot Grigio DOC delle Venezie | sito ufficiale","description":"Drink Italian, feel Italian","publisher":{"@id":"https:\/\/dellevenezie.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dellevenezie.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dellevenezie.it\/#organization","name":"Consorzio vini DOC delle Venezie","url":"https:\/\/dellevenezie.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dellevenezie.it\/#\/schema\/logo\/image\/","url":"https:\/\/dellevenezie.it\/wp-content\/uploads\/2026\/03\/Logo-Consorzio-DOC-Delle-Venezie-cerchio-fondo-bianco-600px.png","contentUrl":"https:\/\/dellevenezie.it\/wp-content\/uploads\/2026\/03\/Logo-Consorzio-DOC-Delle-Venezie-cerchio-fondo-bianco-600px.png","width":600,"height":599,"caption":"Consorzio vini DOC delle Venezie"},"image":{"@id":"https:\/\/dellevenezie.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pinotgrigio.wine","https:\/\/x.com\/delleVenezie","https:\/\/www.instagram.com\/dellevenezie\/","https:\/\/www.facebook.com\/dellevenezie","https:\/\/www.youtube.com\/@dellevenezie"]}]}},"_links":{"self":[{"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/pages\/1968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/comments?post=1968"}],"version-history":[{"count":36,"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/pages\/1968\/revisions"}],"predecessor-version":[{"id":5695,"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/pages\/1968\/revisions\/5695"}],"wp:attachment":[{"href":"https:\/\/dellevenezie.it\/en\/wp-json\/wp\/v2\/media?parent=1968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}